{"id":11386,"date":"2019-06-13T00:00:00","date_gmt":"2019-06-12T22:00:00","guid":{"rendered":"https:\/\/www.swibeco.ch\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/"},"modified":"2024-09-11T15:17:43","modified_gmt":"2024-09-11T13:17:43","slug":"swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card","status":"publish","type":"post","link":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/","title":{"rendered":"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card"},"content":{"rendered":"\n<p>Lausanne, 6. Juni 2019 \u2013 Swibeco, die digitale Plattform f\u00fcr \u00abFlexible Benefits\u00bb, die alle Vorteilsprogramme, Geschenke und steuerfreie Benefits f\u00fcr Mitarbeiter zentralisiert, gibt heute bekannt, dass sie ihre Aktivit\u00e4ten mit BenefitsForYou, dem Schweizer Spezialist f\u00fcr Mahlzeiten-Schecks, zusammenf\u00fchrt und Arbeitnehmern somit k\u00fcnftig das umfassendste digitale Benefits-Paket der Schweiz anbietet.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Swibeco Lunch Card | Annonce de la fusion de BenefitsForYou SA et Swibeco AG\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/f3_7UeJb2cE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Swibeco, ein Pionier auf dem Gebiet der Rabatte und anderer personalisierter Leistungen f\u00fcr Mitarbeiter, hat mit BenefitsForYou den idealen Partner gefunden, um sein Angebot um eine Gehaltszulage f\u00fcr Lebensmitteln zu erweitern. Aus dieser Fusion entsteht die Swibeco Lunch Card. Die Karte weist den Weg in die Zukunft des Verpflegungszuschusses. Sie wird vom jeweiligen Arbeitgeber finanziert und gibt dessen Mitarbeiter eine zus\u00e4tzliche Kaufkraft von bis zu 180 Franken pro Monat (2\u2019160 Franken pro Jahr), die zudem von Sozialversicherungsbeitr\u00e4gen und Steuern befreit sind. Eine attraktive L\u00f6sung, durch welche der Arbeitgeber erhebliche Einsparungen erzielen und gleichzeitig die Kaufkraft seiner Mitarbeiter erh\u00f6hen kann. Sie kann in allen Superm\u00e4rkten, Restaurants, Feinkostgesch\u00e4fte, Kantinen und Schnellrestaurants in der Schweiz, welche Visa-Karten akzeptieren (mehr als 35\u2019000 Betriebe) sowie im benachbarten Ausland eingesetzt werden.<\/p>\n\n\n\n<p>Mit diesem Zusammenschluss wollen Swibeco und BenefitsForYou ihre Position im Schweizer Markt f\u00fcr \u00abFringe Benefits\u00bb st\u00e4rken und ihren Kunden eine globale und integrierte HR-L\u00f6sung f\u00fcr Lohnnebenleistungen anbieten. Die Swibeco Lunch Card, welche der CEO und Gr\u00fcnder von BenefitsForYou, Alexis de Font-R\u00e9aulx, in Zusammenarbeit mit Corn\u00e8rcard und Visa entwickelt hat, passt perfekt zu den bereits von Swibeco angebotenen Dienstleistungen zur Verbesserung des finanziellen Wohlbefindens von Schweizer Angestellten.<\/p>\n\n\n\n<p>\u00ab Unsere bestehenden und potenziellen Kunden suchen nach einfachen und pragmatischen L\u00f6sungen zur Umsetzung von steuerfreien Nebenleistungen. Diese Fusion stellt ein integriertes Instrument dar, das unseren Kunden und ihren Mitarbeiter das Leben leichter macht \u00bb, sagte Ivan Brustlein, CEO und Gr\u00fcnder der Swibeco AG.<\/p>\n\n\n\n<p>Alexis de Font-R\u00e9aulx, der als Direktor zu Swibeco wechselt, begr\u00fc\u00dft die Fusion: \u00ab Die Synergien zwischen unseren Aktivit\u00e4ten sind weitreichend: wir haben die gleichen Kunden, die gleichen Nutzer und das gemeinsame Ziel, echte Innovationen in Bezug auf Vorteilsleistungen f\u00fcr Schweizer Unternehmen und Mitarbeiter zu schaffen. Wir freuen uns darauf, ein dynamisches und ambitioniertes Team zu bilden, mit dem wir starke Werte und eine gemeinsame Vision teilen. \u00bb<\/p>\n\n\n\n<p>Die Fusion von Swibeco und BenefitsForYou wurde mit der Unterst\u00fctzung von Venture Mills mit Sitz in Genf durchgef\u00fchrt.<\/p>\n\n\n\n<p>Swibeco SA<br>Die Gr\u00fcnder sind von einer einfachen Tatsache ausgegangen: die gegenw\u00e4rtigen Verg\u00fctungssysteme bieten keine ausreichende Flexibilit\u00e4t, um Mitarbeiter auf eine motivierende und belohnende Weise aufzuwerten. In der Tat ist die Erh\u00f6hung des Gehalts nicht die einzige Alternative, um den Mitarbeiter eine Anerkennung deutlich zu machen. Vor diesem Hintergrund haben Ivan Brustlein und Alessandro Pian im September 2015 die Swibeco AG gegr\u00fcndet. Swibeco ist die einzige digitale \u201eFringe Benefits\u201c Plattform in der Schweiz, die alle Vorteilsprogramme, Geschenke und steuerfreie Benefits zentralisiert.<\/p>\n\n\n\n<p>BenefitsForYou SA<br>Nach einer detaillierten Analyse des Schweizer Marktes der Mahlzeiten-Schecks stellte Alexis de Font-R\u00e9aulx bedeutende M\u00e4ngel im bestehenden Angebot in Bezug auf Image- und Managementprozesse fest. 2016 entwickelte er zusammen mit Cornercard eine innovative und moderne Alternative zu Mahlzeiten-Schecks in Papierform, um den hohen Anforderungen der Schweizer Unternehmen und Angestellten gerecht zu werden. Diese MealForYou-Karte ist nun die Swibeco Lunch Card und Alexis de Font R\u00e9aulx wird zum Direktor der Swibeco AG ernannt.<\/p>\n\n\n\n<p>Kontaktieren Sie uns f\u00fcr weitere Informationen \u00fcber die Swibeco Lunch Card.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lausanne, 6. Juni 2019 \u2013 Swibeco, die digitale Plattform f\u00fcr \u00abFlexible Benefits\u00bb, die alle Vorteilsprogramme, Geschenke und steuerfreie Benefits f\u00fcr Mitarbeiter zentralisiert, gibt heute bekannt, dass sie ihre Aktivit\u00e4ten mit BenefitsForYou, dem Schweizer Spezialist f\u00fcr Mahlzeiten-Schecks, zusammenf\u00fchrt und Arbeitnehmern somit k\u00fcnftig das umfassendste digitale Benefits-Paket der Schweiz anbietet. Swibeco, ein Pionier auf dem Gebiet der &#8230; <a title=\"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card\" class=\"read-more\" href=\"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/\" aria-label=\"Mehr Informationen \u00fcber Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":35427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-11386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeitgeber-blog","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25","resize-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card | Swibeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card\" \/>\n<meta property=\"og:description\" content=\"Lausanne, 6. Juni 2019 \u2013 Swibeco, die digitale Plattform f\u00fcr \u00abFlexible Benefits\u00bb, die alle Vorteilsprogramme, Geschenke und steuerfreie Benefits f\u00fcr Mitarbeiter zentralisiert, gibt heute bekannt, dass sie ihre Aktivit\u00e4ten mit BenefitsForYou, dem Schweizer Spezialist f\u00fcr Mahlzeiten-Schecks, zusammenf\u00fchrt und Arbeitnehmern somit k\u00fcnftig das umfassendste digitale Benefits-Paket der Schweiz anbietet. Swibeco, ein Pionier auf dem Gebiet der ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/\" \/>\n<meta property=\"og:site_name\" content=\"Swibeco\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-12T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T13:17:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.swibeco.ch\/wp-content\/uploads\/swibeco-opengraph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"713\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"marie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/\"},\"author\":{\"name\":\"marie\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#\\\/schema\\\/person\\\/92bb2205dab47232a98411cfdf405819\"},\"headline\":\"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card\",\"datePublished\":\"2019-06-12T22:00:00+00:00\",\"dateModified\":\"2024-09-11T13:17:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swibeco.ch\\\/wp-content\\\/uploads\\\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg\",\"articleSection\":[\"Der Arbeitgeber-Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/\",\"url\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/\",\"name\":\"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card | Swibeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swibeco.ch\\\/wp-content\\\/uploads\\\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg\",\"datePublished\":\"2019-06-12T22:00:00+00:00\",\"dateModified\":\"2024-09-11T13:17:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.swibeco.ch\\\/wp-content\\\/uploads\\\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg\",\"contentUrl\":\"https:\\\/\\\/www.swibeco.ch\\\/wp-content\\\/uploads\\\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg\",\"width\":713,\"height\":476,\"caption\":\"Swibeco- Les 5 fondamentaux pour de bonnes habitudes alimentaires\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/\",\"name\":\"Swibeco\",\"description\":\"Flexible Benefits for Real Impact\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#organization\",\"name\":\"SWIBECO\",\"url\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.swibeco.ch\\\/wp-content\\\/uploads\\\/logo-swibeco.svg\",\"contentUrl\":\"https:\\\/\\\/www.swibeco.ch\\\/wp-content\\\/uploads\\\/logo-swibeco.svg\",\"width\":300,\"height\":110,\"caption\":\"SWIBECO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swibeco\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.swibeco.ch\\\/de\\\/#\\\/schema\\\/person\\\/92bb2205dab47232a98411cfdf405819\",\"name\":\"marie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04cbea7620b9a449ff4e02ff927e2aec7c3b555bf31036533b08837c34d28ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04cbea7620b9a449ff4e02ff927e2aec7c3b555bf31036533b08837c34d28ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04cbea7620b9a449ff4e02ff927e2aec7c3b555bf31036533b08837c34d28ed?s=96&d=mm&r=g\",\"caption\":\"marie\"},\"sameAs\":[\"https:\\\/\\\/www.swibeco.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card | Swibeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/","og_locale":"de_DE","og_type":"article","og_title":"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card","og_description":"Lausanne, 6. Juni 2019 \u2013 Swibeco, die digitale Plattform f\u00fcr \u00abFlexible Benefits\u00bb, die alle Vorteilsprogramme, Geschenke und steuerfreie Benefits f\u00fcr Mitarbeiter zentralisiert, gibt heute bekannt, dass sie ihre Aktivit\u00e4ten mit BenefitsForYou, dem Schweizer Spezialist f\u00fcr Mahlzeiten-Schecks, zusammenf\u00fchrt und Arbeitnehmern somit k\u00fcnftig das umfassendste digitale Benefits-Paket der Schweiz anbietet. Swibeco, ein Pionier auf dem Gebiet der ... Lire plus","og_url":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/","og_site_name":"Swibeco","article_published_time":"2019-06-12T22:00:00+00:00","article_modified_time":"2024-09-11T13:17:43+00:00","og_image":[{"width":713,"height":476,"url":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/swibeco-opengraph.jpg","type":"image\/jpeg"}],"author":"marie","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"marie","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#article","isPartOf":{"@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/"},"author":{"name":"marie","@id":"https:\/\/www.swibeco.ch\/de\/#\/schema\/person\/92bb2205dab47232a98411cfdf405819"},"headline":"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card","datePublished":"2019-06-12T22:00:00+00:00","dateModified":"2024-09-11T13:17:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/"},"wordCount":580,"publisher":{"@id":"https:\/\/www.swibeco.ch\/de\/#organization"},"image":{"@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg","articleSection":["Der Arbeitgeber-Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/","url":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/","name":"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card | Swibeco","isPartOf":{"@id":"https:\/\/www.swibeco.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#primaryimage"},"image":{"@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg","datePublished":"2019-06-12T22:00:00+00:00","dateModified":"2024-09-11T13:17:43+00:00","breadcrumb":{"@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#primaryimage","url":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg","contentUrl":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/blog-swibeco-5-fondamentaux-bonnes-habitudes-alimentaires.jpg","width":713,"height":476,"caption":"Swibeco- Les 5 fondamentaux pour de bonnes habitudes alimentaires"},{"@type":"BreadcrumbList","@id":"https:\/\/www.swibeco.ch\/de\/swibeco-und-benefitsforyou-fusionieren-swibeco-lunch-card\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.swibeco.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Swibeco und BenefitsForYou fusionieren und lancieren gemeinsam die Swibeco Lunch Card"}]},{"@type":"WebSite","@id":"https:\/\/www.swibeco.ch\/de\/#website","url":"https:\/\/www.swibeco.ch\/de\/","name":"Swibeco","description":"Flexible Benefits for Real Impact","publisher":{"@id":"https:\/\/www.swibeco.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.swibeco.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.swibeco.ch\/de\/#organization","name":"SWIBECO","url":"https:\/\/www.swibeco.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.swibeco.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/logo-swibeco.svg","contentUrl":"https:\/\/www.swibeco.ch\/wp-content\/uploads\/logo-swibeco.svg","width":300,"height":110,"caption":"SWIBECO"},"image":{"@id":"https:\/\/www.swibeco.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/swibeco\/"]},{"@type":"Person","@id":"https:\/\/www.swibeco.ch\/de\/#\/schema\/person\/92bb2205dab47232a98411cfdf405819","name":"marie","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e04cbea7620b9a449ff4e02ff927e2aec7c3b555bf31036533b08837c34d28ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e04cbea7620b9a449ff4e02ff927e2aec7c3b555bf31036533b08837c34d28ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e04cbea7620b9a449ff4e02ff927e2aec7c3b555bf31036533b08837c34d28ed?s=96&d=mm&r=g","caption":"marie"},"sameAs":["https:\/\/www.swibeco.ch"]}]}},"_links":{"self":[{"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/posts\/11386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/comments?post=11386"}],"version-history":[{"count":0,"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/posts\/11386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/media\/35427"}],"wp:attachment":[{"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/media?parent=11386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/categories?post=11386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swibeco.ch\/de\/wp-json\/wp\/v2\/tags?post=11386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}